{"id":1312,"date":"2022-08-09T16:34:38","date_gmt":"2022-08-09T14:34:38","guid":{"rendered":"https:\/\/corona-strategie.at\/wp\/?post_type=tribe_events&#038;p=1312"},"modified":"2022-08-09T20:48:10","modified_gmt":"2022-08-09T18:48:10","slug":"ggi-wanderung-steiermark-geologisch-kraeuterkundlicher-spaziergang-zum-kraftplatz-am-silberberg","status":"publish","type":"tribe_events","link":"https:\/\/ggi-initiative.at\/wp\/veranstaltung\/ggi-wanderung-steiermark-geologisch-kraeuterkundlicher-spaziergang-zum-kraftplatz-am-silberberg\/","title":{"rendered":"GGI Wanderung Steiermark \u2022 Geologisch-kr\u00e4uterkundlicher Spaziergang zum Kraftplatz am Silberberg"},"content":{"rendered":"<div class=\"bi6gxh9e\"><span class=\"d2edcug0 hpfvmrgz qv66sw1b c1et5uql oi732d6d ik7dh3pa ht8s03o8 jq4qci2q a3bd9o3v b1v8xokw oo9gr5id\">Gemeinsam unterwegs<\/span><\/div>\n<div class=\"bi6gxh9e\">\n<p><span class=\"d2edcug0 hpfvmrgz qv66sw1b c1et5uql oi732d6d ik7dh3pa ht8s03o8 o3w64lxj b2s5l15y b1v8xokw oo9gr5id\"><b>GGI Themenwanderungen &#8211; Gesund sein<\/b><\/span><\/p>\n<\/div>\n<div class=\"jei6r52m\">\n<p><span class=\"d2edcug0 hpfvmrgz qv66sw1b c1et5uql oi732d6d ik7dh3pa ht8s03o8 jq4qci2q a3bd9o3v b1v8xokw oo9gr5id\"><span class=\"d2edcug0 hpfvmrgz qv66sw1b c1et5uql oi732d6d ik7dh3pa ht8s03o8 jq4qci2q a3bd9o3v b1v8xokw m9osqain\"><i>Leben wie ein Baum, einzeln und frei, und geschwisterlich wie ein Wald, das ist unsere Sehnsucht.<br \/>\n<\/i>N\u00e2z\u0131m Hikmet<\/span><\/span><\/p>\n<\/div>\n<div class=\"bi6gxh9e\"><span class=\"d2edcug0 hpfvmrgz qv66sw1b c1et5uql oi732d6d ik7dh3pa ht8s03o8 jq4qci2q a3bd9o3v b1v8xokw oo9gr5id\">Wir, die GGI, verstehen uns als eine soziale und naturverbundene Bewegung, die f\u00fcr ein gesundes, selbstbestimmtes und vitales Leben, eine freie Gesellschaft, f\u00fcr Grund- und Menschenrechte sowie einen achtvollen Umgang mit der Natur einsteht.<\/span><\/div>\n<div class=\"bi6gxh9e\"><span class=\"d2edcug0 hpfvmrgz qv66sw1b c1et5uql oi732d6d ik7dh3pa ht8s03o8 jq4qci2q a3bd9o3v b1v8xokw oo9gr5id\">Mit anregenden Themenwanderungen wollen wir ganzheitliche Erfahrungen und Perspektiven erm\u00f6glichen. Die Wanderungen finden in den n\u00e4chsten Wochen und Monaten in den Bundesl\u00e4ndern mit jeweils unterschiedlichen Schwerpunkten statt. Allen gemeinsam ist: es geht um ein gesundes Sein. Nach zweieinhalb Jahren Fixierung auf Krankheit ist es h\u00f6chste Zeit, GESUNDHEIT in den Mittelpunkt unserer Sichtweisen und Aktivit\u00e4ten zu stellen.<\/span><\/div>\n<div class=\"bi6gxh9e\"><span class=\"d2edcug0 hpfvmrgz qv66sw1b c1et5uql oi732d6d ik7dh3pa ht8s03o8 jq4qci2q a3bd9o3v b1v8xokw oo9gr5id\">Wir sp\u00fcren, dass Bewegung gesund ist, den Geist \u00f6ffnet, uns lebendig macht. Im Rahmen unserer Themenwanderungen regen wir nicht nur unser Lymph- und Immunsystem an, sondern wollen auch ganzheitliche Erfahrungen erm\u00f6glichen sowie Perspektiven f\u00fcr individuelle und gesellschaftliche Gesundung er\u00f6ffnen.<\/span><\/div>\n<div class=\"bi6gxh9e\"><span class=\"d2edcug0 hpfvmrgz qv66sw1b c1et5uql oi732d6d ik7dh3pa ht8s03o8 jq4qci2q a3bd9o3v b1v8xokw oo9gr5id\">Bei den Wanderungen nehmen wir die Natur mit allen Sinnen wahr \u2013 und damit auch uns selbst \u2013 als Ansto\u00df f\u00fcr eine heilsame Verbindung. Gelebte Verbundenheit k\u00f6nnen wir nicht nur in alten Weisheiten oder in Traditionen indigener Kulturen finden. Wir k\u00f6nnen sie hier und jetzt und \u00fcberall, auch in uns selbst, entdecken. Wir sind die Gestalter:innen unserer k\u00f6rperlichen und geistigen Gesundheit und eines gesunden Miteinanders.<\/span><\/div>\n<div class=\"bi6gxh9e\"><strong><br \/>\nSteiermark \u2022 10. September \u2022 Gro\u00dfst\u00fcbing\/Silberberg<br \/>\n10.00 \u2013 13:00<br \/>\n<\/strong><strong>Geologisch-kr\u00e4uterkundlicher Spaziergang zum Kraftplatz am Silberberg<\/strong><\/div>\n<p>Gemeinsam mit <a title=\"http:\/\/www.wonderfulgardens.at\/\" href=\"http:\/\/www.wonderfulgardens.at\/\" target=\"_blank\" rel=\"noreferrer nofollow noopener\">Stefan Haring<\/a> von der GGI werden wir bei einem ca 3-st\u00fcndigen Spaziergang entlang von Forststra\u00dfen und J\u00e4gersteigen auf ca 1.000 m Seeh\u00f6he die Naturmagie mit allen Sinnen erfahren und dabei die scheinbar verschollene schamanische Kultur des Alpenraumes &#8211; altes Kr\u00e4uterwissen und die Kunst der Geomantie &#8211; wiederentdecken.<\/p>\n<p>Treffpunkt: 10.00 Uhr Pfarrhof Gro\u00dfst\u00fcbing<br \/>\nEnde:<br \/>\nLeitung:\u00a0 Stefan Haring (GGI Steiermark)<br \/>\nAnmeldung &amp; Information: Stefan Haring \u2022 stefanharing@protonmail.com \u2022 0699-10918711<br \/>\n<a href=\"http:\/\/www.wonderfulgardens.at\/\">http:\/\/www.wonderfulgardens.at\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gemeinsam unterwegs GGI Themenwanderungen &#8211; Gesund sein Leben wie ein Baum, einzeln [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1322,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-1312","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ggi-initiative.at\/wp\/wp-json\/wp\/v2\/tribe_events\/1312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ggi-initiative.at\/wp\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/ggi-initiative.at\/wp\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/ggi-initiative.at\/wp\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":3,"href":"https:\/\/ggi-initiative.at\/wp\/wp-json\/wp\/v2\/tribe_events\/1312\/revisions"}],"predecessor-version":[{"id":1316,"href":"https:\/\/ggi-initiative.at\/wp\/wp-json\/wp\/v2\/tribe_events\/1312\/revisions\/1316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ggi-initiative.at\/wp\/wp-json\/wp\/v2\/media\/1322"}],"wp:attachment":[{"href":"https:\/\/ggi-initiative.at\/wp\/wp-json\/wp\/v2\/media?parent=1312"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ggi-initiative.at\/wp\/wp-json\/wp\/v2\/tags?post=1312"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/ggi-initiative.at\/wp\/wp-json\/wp\/v2\/tribe_events_cat?post=1312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}